{"id":131,"date":"2008-07-16T15:59:30","date_gmt":"2008-07-16T13:59:30","guid":{"rendered":"https:\/\/enricgine.cat\/es\/?p=131"},"modified":"2026-05-13T14:07:10","modified_gmt":"2026-05-13T12:07:10","slug":"dependencia-o-independencia-esto-es-la-pregunta","status":"publish","type":"post","link":"https:\/\/enricgine.cat\/es\/dependencia-o-independencia-esto-es-la-pregunta\/","title":{"rendered":"Dependencia o Independencia esta es la cuesti\u00f3n"},"content":{"rendered":"\r\n<p class=\"has-text-align-right\" style=\"text-align: right;\"><a href=\"mailto:enric@enricgine.cat\">enric@enricgine.cat<\/a><\/p>\r\n\r\n\r\n\r\n<p><strong>Dependencia o Independencia, \u00e9sta es la cuesti\u00f3n<\/strong><\/p>\r\n<p>Cada uno tiene su tesis sobre la Independencia, pero para m\u00ed es algo especial y lo uso muy a menudo.<\/p>\r\n<p>Pero primero voy a explicar el problema m\u00e1s importante que tenemos los catalanes, y es que nuestra cultura est\u00e1 desaparecien\u00addo, sin que a Espa\u00f1a le preocupe lo m\u00e1s m\u00ednimo, sino al contra\u00adrio, es la principal causa de que este genocidio se realice, y ella hace todo lo posible para que as\u00ed sea, tal como ella ya ha hecho en infinidad de pa\u00edses, en esto tiene mucha experiencia, por esto: <strong>Dependencia o independencia, esa es la cuesti\u00f3n.<\/strong> Para m\u00ed, ser o no ser espa\u00f1ol no tiene importancia, lo que s\u00ed tiene importancia es perseverar en mi cultura catalana, y, por lo visto, la adminis\u00adtraci\u00f3n de Madrid no enriquece ni promociona la Cultura Catalana, sino al contrario, y entonces parece que la \u00fanica salida para la conservaci\u00f3n de nuestra Cultura es la Independencia.<\/p>\r\n<p>Y en esta, hay dos formas de posicionarseu, una es ser depen\u00addiente y la otra es ser independiente, la dependiente es la que los catalanes hemos utilizado en estos \u00faltimos 300 a\u00f1os, es dar un dinero a Espa\u00f1a para que nos administre por 60 millones de euros al d\u00eda, ya que los catalanes no somos muy listos para admi\u00adnistrarnos, y como hay gente m\u00e1s lista que nosotros, como los llamados <strong>espa\u00f1oles<\/strong>, o los castellanos, ellos nos hacen ese favor o trabajo, ahora nos cobran ese dinero por administrar <strong>Catalunya<\/strong>, pero el problema es que somos una colonia, ya que perdimos la guerra, y hasta ahora pagamos las consecuencias, pero tenemos que buscar la manera de poder defender nuestra Cultura, tal vez no somos tan tontos como creemos y podr\u00edamos administrarnos nosotros mismos y as\u00ed nos ahorrar\u00edamos todo ese dinero, estas son las dos posibilidades que tenemos, yo creo que no hay opci\u00f3n, que la mejor es la Independencia, Catalu\u00f1a ya es mayor de edad y sabe administrar ella misma sus recursos sin necesidad de nadie, adem\u00e1s, es algo incomprensible que unas personas que no tienen nada que ver con <strong>Catalunya <\/strong>sepan c\u00f3mo solucionar los problemas de los catalanes, por ejemplo, cu\u00e1ntas l\u00edneas de trenes necesitan los catalanes, qu\u00e9 horarios, cu\u00e1ntas carreteras o autopistas o aero\u00adpuertos, ademas del idioma que esta ya en minoria, y as\u00ed una lista interminable de cosas que se hacen desde Madrid, como fomentar el espa\u00f1ol, porque dicen que Catalunya es Espa\u00f1a. \u00bfNo ser\u00eda mejor que los catalanes nos administr\u00e1semos nosotros de acuerdo con nuestras necesidades? Dependencia o independencia es sin\u00f3nimo de Administraci\u00f3n, y los de Madrid quieren administrarnos porque los administradores se quedan con una mejor parte del pastel que los administrados, sin em\u00adbargo, elemental, m\u00edster Watson, dependencia o independencia tambi\u00e9n significa lo que la misma palabra significa, que o de\u00adpendes o no dependes.<strong> Catalunya<\/strong> <strong>ahora depende de Madrid, <\/strong>y eso quiere decir que Madrid administra <strong><em>Catalunya<\/em><\/strong>, porque esta depende de ella, este dinero que los espa\u00f1oles nos expolian lo ne\u00adcesitamos para hacer carreteras, tener una buena red ferroviaria, buenos aeropuertos, buena sanidad p\u00fablica, buenas escuelas, etc., etc., 60 millones de euros diarios es mucho, mucho dinero, se habla mucho de Independencia, pero lo que queremos es que los catalanes nos administremos, nosotros mismos, di independen\u00adcia o administraci\u00f3n, adem\u00e1s, esta administraci\u00f3n no es querida por los catalanes, ya que fue una imposici\u00f3n de guerra, dado que los catalanes la perdieron, y desde entonces somos una colonia y como tal es administrada por los que ganaron la guerra, y, dicho sea de paso, la perdimos por traici\u00f3n de unos pa\u00edses que nos de\u00adjaron en la estacada.<\/p>\r\n<p>Queremos que en Catalu\u00f1a se hable nuestro idioma, que es el catal\u00e1n, nosotros somos una naci\u00f3n, y como naci\u00f3n tenemos una cultura, un idioma, unas costumbres, al igual que otra, como la castellana, gallega, vasca, francesa, alemana, etc., y lo \u00fanico que los catalanes queremos es administrarnos nosotros mismos, y preservar nuestra cultura, que est\u00e1, como ya he dicho, desapare\u00adciendo, otra vez <strong>independencia<\/strong> es igual a <strong>administraci\u00f3n,<\/strong> y, si no nos administramos, nuestra cultura desaparecer\u00e1.<\/p>\r\n<p>Enric Gin\u00e9 i Orengo<\/p>\r\n\r\n\r\n\r\n<p>&nbsp;<\/p>\r\n","protected":false},"excerpt":{"rendered":"<p>enric@enricgine.cat Dependencia o Independencia, \u00e9sta es la cuesti\u00f3n Cada uno tiene su tesis sobre la Independencia, pero para m\u00ed es algo especial y lo uso muy a menudo. Pero primero voy a explicar el problema m\u00e1s importante que tenemos los &hellip; <a href=\"https:\/\/enricgine.cat\/es\/dependencia-o-independencia-esto-es-la-pregunta\/\">Sigue leyendo <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-131","post","type-post","status-publish","format-standard","hentry","category-sin-categoria"],"_links":{"self":[{"href":"https:\/\/enricgine.cat\/es\/wp-json\/wp\/v2\/posts\/131","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enricgine.cat\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/enricgine.cat\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/enricgine.cat\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/enricgine.cat\/es\/wp-json\/wp\/v2\/comments?post=131"}],"version-history":[{"count":17,"href":"https:\/\/enricgine.cat\/es\/wp-json\/wp\/v2\/posts\/131\/revisions"}],"predecessor-version":[{"id":1188,"href":"https:\/\/enricgine.cat\/es\/wp-json\/wp\/v2\/posts\/131\/revisions\/1188"}],"wp:attachment":[{"href":"https:\/\/enricgine.cat\/es\/wp-json\/wp\/v2\/media?parent=131"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/enricgine.cat\/es\/wp-json\/wp\/v2\/categories?post=131"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/enricgine.cat\/es\/wp-json\/wp\/v2\/tags?post=131"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}